{"id":33,"count":1,"description":"","link":"https:\/\/www.fabricareofgreenville.com\/blog\/category\/discounts-specials\/","name":"Discounts &amp; Specials","slug":"discounts-specials","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Discounts &amp; Specials Archives | Fabricare Of Greenville<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fabricareofgreenville.com\/blog\/category\/discounts-specials\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Discounts &amp; Specials Archives | Fabricare Of Greenville\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fabricareofgreenville.com\/blog\/category\/discounts-specials\/\" \/>\n<meta property=\"og:site_name\" content=\"Fabricare Of Greenville\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.fabricareofgreenville.com\\\/blog\\\/category\\\/discounts-specials\\\/\",\"url\":\"https:\\\/\\\/www.fabricareofgreenville.com\\\/blog\\\/category\\\/discounts-specials\\\/\",\"name\":\"Discounts &amp; Specials Archives | Fabricare Of Greenville\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fabricareofgreenville.com\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fabricareofgreenville.com\\\/blog\\\/category\\\/discounts-specials\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fabricareofgreenville.com\\\/blog\\\/category\\\/discounts-specials\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.fabricareofgreenville.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Discounts &amp; Specials\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fabricareofgreenville.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.fabricareofgreenville.com\\\/blog\\\/\",\"name\":\"Fabricare Of Greenville\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.fabricareofgreenville.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fabricareofgreenville.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.fabricareofgreenville.com\\\/blog\\\/#organization\",\"name\":\"Fabricare Of Greenville\",\"url\":\"https:\\\/\\\/www.fabricareofgreenville.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.fabricareofgreenville.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.fabricareofgreenville.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/main-logo.png\",\"contentUrl\":\"https:\\\/\\\/www.fabricareofgreenville.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/main-logo.png\",\"width\":240,\"height\":66,\"caption\":\"Fabricare Of Greenville\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fabricareofgreenville.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Fabricare-of-Greenville-526316991152894\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/fabricare-of-greenville\\\/about\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Discounts &amp; Specials Archives | Fabricare Of Greenville","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fabricareofgreenville.com\/blog\/category\/discounts-specials\/","og_locale":"en_US","og_type":"article","og_title":"Discounts &amp; Specials Archives | Fabricare Of Greenville","og_url":"https:\/\/www.fabricareofgreenville.com\/blog\/category\/discounts-specials\/","og_site_name":"Fabricare Of Greenville","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.fabricareofgreenville.com\/blog\/category\/discounts-specials\/","url":"https:\/\/www.fabricareofgreenville.com\/blog\/category\/discounts-specials\/","name":"Discounts &amp; Specials Archives | Fabricare Of Greenville","isPartOf":{"@id":"https:\/\/www.fabricareofgreenville.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.fabricareofgreenville.com\/blog\/category\/discounts-specials\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.fabricareofgreenville.com\/blog\/category\/discounts-specials\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fabricareofgreenville.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Discounts &amp; Specials"}]},{"@type":"WebSite","@id":"https:\/\/www.fabricareofgreenville.com\/blog\/#website","url":"https:\/\/www.fabricareofgreenville.com\/blog\/","name":"Fabricare Of Greenville","description":"","publisher":{"@id":"https:\/\/www.fabricareofgreenville.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fabricareofgreenville.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.fabricareofgreenville.com\/blog\/#organization","name":"Fabricare Of Greenville","url":"https:\/\/www.fabricareofgreenville.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.fabricareofgreenville.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.fabricareofgreenville.com\/blog\/wp-content\/uploads\/2019\/08\/main-logo.png","contentUrl":"https:\/\/www.fabricareofgreenville.com\/blog\/wp-content\/uploads\/2019\/08\/main-logo.png","width":240,"height":66,"caption":"Fabricare Of Greenville"},"image":{"@id":"https:\/\/www.fabricareofgreenville.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Fabricare-of-Greenville-526316991152894\/","https:\/\/www.linkedin.com\/company\/fabricare-of-greenville\/about\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.fabricareofgreenville.com\/blog\/wp-json\/wp\/v2\/categories\/33","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fabricareofgreenville.com\/blog\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.fabricareofgreenville.com\/blog\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.fabricareofgreenville.com\/blog\/wp-json\/wp\/v2\/posts?categories=33"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}